
{"id":223,"date":"2005-09-26T17:28:40","date_gmt":"2005-09-26T15:28:40","guid":{"rendered":"http:\/\/www.stadthaushotel.com\/Aktuell\/?p=223"},"modified":"2018-04-16T19:57:12","modified_gmt":"2018-04-16T19:57:12","slug":"internetauftritt-des-stadthaushotel-wird-barrierefrei","status":"publish","type":"post","link":"https:\/\/stadthaushotel.de\/aktuell\/internetauftritt-des-stadthaushotel-wird-barrierefrei\/","title":{"rendered":"Internetauftritt des Stadthaushotel wird barrierefrei"},"content":{"rendered":"<p>Behinderten- und Benutzerfreundlichkeit: Das Motto des ber\u00fchmtesten Integrationshotel Europas gilt nun auch f\u00fcr seinen Internetauftritt. \u201eUnser Entwicklerteam hatte eine harte Nuss zu knacken&hellip;\u201c meint Thomas Ulrich, technischer Leiter des Projekts. \u201e&hellip;aber Dank unseres erfahrenen Entwicklerteams haben wir es geschafft, eine harmonische Synthese zwischen ansprechendem <span lang=\"en\" xml:lang=\"en\">Layout<\/span> und barrierefreiem Zugang zu schaffen.\u201c <!--more--><\/p>\n<p>Der neue Auftritt erf\u00fcllt dabei fast vollst\u00e4ndig die strengen Auflagen des \u201e<span lang=\"en\" xml:lang=\"en\">Web Content Accessibility Guidelines 1.0.<\/span>\u201c Hierbei handelt es sich um eine <span lang=\"en\" xml:lang=\"en\">Check<\/span>liste f\u00fcr Barrierefreie Web-Inhalte, des 1994 gegr\u00fcndeten <span lang=\"en\" xml:lang=\"en\">World Wide Web Consortium (W3C)<\/span>, welches dar\u00fcber wacht, dass die Techniken des <span lang=\"en\" xml:lang=\"en\">World Wide Web<\/span> weltweit standardisiert werden. Vorsitzender ist Tim Berners-Lee, der auch als der Erfinder des <span lang=\"en\" xml:lang=\"en\">World Wide Web<\/span> bekannt ist. Selbstverst\u00e4ndlich wurde auch die nationale \u201eBarrierefreie Informationstechnik-Verordnung \u2013 BITV\u201c vom 17. Juli 2002 nach dem Behindertengleichstellungsgesetz umgesetzt. Sie regelt <abbr title=\"zum Beispiel\">z. B.<\/abbr> das alle Internetseiten des Bundes bis zum 31. Dezember 2005 barrierefrei sein m\u00fcssen.<\/p>\n<p>Alle auf der Seite benutzten Dokumente sind valide <acronym title=\"Extensible Hypertext Markup Language\" lang=\"en\" xml:lang=\"en\">XHTML<\/acronym>-Dokumente (eine moderne Form der <acronym title=\"Hypertext Markup Language\" lang=\"en\" xml:lang=\"en\">HTML<\/acronym>-Seitenbeschreibungssprache). Zur Gestaltung dienen so genannte <acronym title=\"Cascading Style Sheets\" lang=\"en\" xml:lang=\"en\">CSS<\/acronym>-Dateien (<span lang=\"en\" xml:lang=\"en\">Cascading Style Sheets<\/span>). Durch diese Trennung von Form und Inhalt wird der Zugang zur <span lang=\"en\" xml:lang=\"en\">Site<\/span> mit alternativen <span lang=\"en\" xml:lang=\"en\">Browsern<\/span>, wie zum Beispiel Ger\u00e4ten zur Ausgabe in Brailleschrift (Blindenschrift), Textbrowsern, oder Ger\u00e4ten die Internetseiten vorlesen, erleichtert. Die Seiten wurden von Interneterfahrener Personen mit <span lang=\"en\" xml:lang=\"en\">Handicap<\/span> (sowohl Blinde und Sehbehinderte, als auch Bewegungseingeschr\u00e4nkte) auf ihre Praxistauglichkeit \u00fcberpr\u00fcft. <\/p>\n<p>Neben hochwertigen Fotos, Informationen zum Hotel und seiner Geschichte, finden sich allerlei n\u00fctzliche \u201eKleinigkeiten\u201c (<abbr title=\"zum Beispiel\">z. B.<\/abbr> ein W\u00f6rterbuch, Akronymerkl\u00e4rungen). Onlinebuchungsanfragen, <span lang=\"en\" xml:lang=\"en\">Callback<\/span>-Service und Routenplaner runden das durchweg professionelle Angebot ab.<\/p>\n<p>Auch Axel Gra\u00dfmann, Gesch\u00e4ftsf\u00fchrer des Hotels, ist zufrieden und stolz \u201eeinen der besten und sch\u00f6nsten barrierefreien Hotelinternetauftritte\u201c im deutschsprachigen Web zu haben.<\/p>\n<p>      <span class=\"fett\">Zum Hintergrund<br \/>\n    <\/span>    <\/p>\n<p>1987 schlossen sich Eltern von acht unterschiedlich stark behinderten Kindern in der Initiative Werkstadthaus <abbr title=\"eingetragener Verein\">e. V.<\/abbr> zusammen und realisierten ein bis dahin einzigartiges Projekt in Europa, das Stadthaushotel Hamburg \u2013 Anders und gut! Seit September 1993 wohnen und arbeiten hier behinderte Menschen unter einem Dach. Viel hat sich seit dem getan \u2013 Doch die Freundlichkeit, Freude und Professionalit\u00e4t sind geblieben. Die Arbeit der Hotelmitarbeiter wird heute von erfahrenden Hotelfachkr\u00e4ften begleitet.<\/p>\n<p>Seit Juni 2005 ist das Stadthaushotel Hamburg ein Unternehmen der jugend hilft jugend-Arbeit gemeinn\u00fctzige <acronym title=\"Gesellschaft mit beschr\u00e4nkter Haftung\">GmbH<\/acronym>, die eine hunderprozentige Tochter von <a href=\"http:\/\/www.jugend-hilft-jugend.de\" title=\"Zum Internetauftritt von jugend hilft jugend e. V.\"><img loading=\"lazy\" src=\"https:\/\/www.mediathek.jhj.de\/layoutimages\/extern.gif\" alt=\"Externer Link\" width=\"13\" height=\"12\" class=\"img_link\" \/>&nbsp;jugend-hilft-jugend <abbr title=\"eingetragener Verein\">e. V.<\/abbr><\/a> ist. Seit 1970 ist der Verein \u2013 zun\u00e4chst \u2013 nur als Drogenhilfetr\u00e4ger \u2013 in Hamburg mit seinen Projekten bestrebt, Menschen, die, es im Leben bislang nicht so gut getroffen haben, wieder auf die Beine zu helfen, ihnen ein selbstbestimmtes Dasein zu erm\u00f6glichen. Schwerpunkt war immer die Reintegration in Arbeit, als halt- und sinngebender Faktor im Leben. Aus diesem Grund hat der Verein in den vergangenen Jahren seine Projekte in diesem Bereich ausgebaut und ist nun auch ein \u2013 weit \u00fcber die Hansestadt hinaus \u2013 anerkannter Besch\u00e4ftigungstr\u00e4ger.<\/p>\n<p><a href=\"http:\/\/validator.w3.org\/check?uri=referer\"  title=\"Zur XHTML Validator Seite http:\/\/validator.w3.org\/\"><img loading=\"lazy\" src=\"https:\/\/www.stadthaushotel.com\/images\/valid-xhtml10.png\" alt=\"Bildzeichen f\u00fc Valid XHTML 1.0!\" width=\"88\" height=\"31\" class=\"img_link\" \/><\/a> <a href=\"http:\/\/jigsaw.w3.org\/css-validator\"   title=\"Zur CSS Validatorseite auf http:\/\/jigsaw.w3.org\"> <img src=\"https:\/\/www.stadthaushotel.com\/images\/vcss.gif\" alt=\"Bildzeichen f\u00fc Valid CSS!\" class=\"img_link\" style=\"border:0;width:88px;height:31px\"  \/><\/a>  <a href=\"http:\/\/www.w3.org\/Consortium\/Offices\/Germany\/Trans\/WAI\/webinhalt.html\"  title=\"Zur Seite mit der deutsche \u00dcbersetzung der Web Content Accessibility Guidelines 1.0\"><img src=\"https:\/\/www.stadthaushotel.com\/images\/wcag1AAA.png\" alt=\"Bildzeichen f\u00fc Valid Accessibility!\" class=\"img_link\" style=\"border:0;width:88px;height:31px\"  \/><\/a> <a href=\"http:\/\/webxact.watchfire.com\/\" title=\"Zur Internetseite: http:\/\/webxact.watchfire.com \"><img src=\"https:\/\/www.stadthaushotel.com\/images\/approved_aaa.gif\" alt=\"Bildzeichen f\u00fc Valid Bobby\" class=\"img_link\" style=\"border:0;width:88px; height:31px\" title=\"Zur Internetsite von watchfire\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Behinderten- und Benutzerfreundlichkeit: Das Motto des ber\u00fchmtesten Integrationshotel Europas gilt nun auch f\u00fcr seinen Internetauftritt. \u201eUnser Entwicklerteam hatte eine harte Nuss zu knacken&hellip;\u201c meint Thomas Ulrich, technischer Leiter des Projekts. \u201e&hellip;aber Dank unseres erfahrenen Entwicklerteams haben wir es geschafft, eine harmonische Synthese zwischen ansprechendem Layout und barrierefreiem Zugang zu schaffen.\u201c<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/posts\/223"}],"collection":[{"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":0,"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/posts\/223\/revisions"}],"wp:attachment":[{"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/media?parent=223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/categories?post=223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stadthaushotel.de\/aktuell\/wp-json\/wp\/v2\/tags?post=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}